{"id":22502,"date":"2023-12-02T22:00:42","date_gmt":"2023-12-02T22:00:42","guid":{"rendered":"https:\/\/www.immomallorca.es\/immobilien\/palma-santa-catalina-casa-del-pescador-alquiler\/"},"modified":"2025-08-28T12:34:01","modified_gmt":"2025-08-28T12:34:01","slug":"palma-santa-catalina-casa-del-pescador-alquiler","status":"publish","type":"immobilien","link":"https:\/\/www.immomallorca.es\/es\/inmuebles\/palma-santa-catalina-casa-del-pescador-alquiler\/","title":{"rendered":"Palma &#8211; Santa Catalina &#8211; Casa del pescador &#8211; Alquiler"},"content":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"immobilien_kategorie":[106,102],"angebotsart":[116],"class_list":["post-22502","immobilien","type-immobilien","status-publish","format-standard","hentry","immobilien_kategorie-casa","immobilien_kategorie-casa-de-pueblo","angebotsart-alquilar"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/immobilien\/22502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/types\/immobilien"}],"author":[{"embeddable":true,"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/immobilien\/22502\/revisions"}],"predecessor-version":[{"id":33671,"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/immobilien\/22502\/revisions\/33671"}],"wp:attachment":[{"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/media?parent=22502"}],"wp:term":[{"taxonomy":"immobilien_kategorie","embeddable":true,"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/immobilien_kategorie?post=22502"},{"taxonomy":"angebotsart","embeddable":true,"href":"https:\/\/www.immomallorca.es\/es\/wp-json\/wp\/v2\/angebotsart?post=22502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}