{"id":22532,"date":"2023-12-02T22:00:41","date_gmt":"2023-12-02T22:00:41","guid":{"rendered":"https:\/\/www.immomallorca.es\/immobilien\/palma-rental-in-la-lonja\/"},"modified":"2025-09-02T08:46:41","modified_gmt":"2025-09-02T08:46:41","slug":"palma-rental-in-la-lonja","status":"publish","type":"immobilien","link":"https:\/\/www.immomallorca.es\/en\/properties\/palma-rental-in-la-lonja\/","title":{"rendered":"Palma Rental in La Lonja"},"content":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"immobilien_kategorie":[],"angebotsart":[115],"class_list":["post-22532","immobilien","type-immobilien","status-publish","format-standard","hentry","angebotsart-rent"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/immobilien\/22532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/types\/immobilien"}],"author":[{"embeddable":true,"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":1,"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/immobilien\/22532\/revisions"}],"predecessor-version":[{"id":33672,"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/immobilien\/22532\/revisions\/33672"}],"wp:attachment":[{"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/media?parent=22532"}],"wp:term":[{"taxonomy":"immobilien_kategorie","embeddable":true,"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/immobilien_kategorie?post=22532"},{"taxonomy":"angebotsart","embeddable":true,"href":"https:\/\/www.immomallorca.es\/en\/wp-json\/wp\/v2\/angebotsart?post=22532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}