{"id":30350,"date":"2025-03-02T13:32:30","date_gmt":"2025-03-02T13:32:30","guid":{"rendered":"https:\/\/www.immomallorca.es\/?post_type=immobilien&#038;p=30350"},"modified":"2025-03-08T19:41:15","modified_gmt":"2025-03-08T19:41:15","slug":"palma-vermietung-in-son-amadams","status":"publish","type":"immobilien","link":"https:\/\/www.immomallorca.es\/de\/immobilien\/palma-vermietung-in-son-amadams\/","title":{"rendered":"Palma &#8211; Vermietung in Son Amadams"},"content":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"template":"","format":"standard","meta":{"_acf_changed":false},"immobilien_kategorie":[38,3],"angebotsart":[43],"class_list":["post-30350","immobilien","type-immobilien","status-publish","format-standard","hentry","immobilien_kategorie-apartment","immobilien_kategorie-wohnungen","angebotsart-vermietung"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/immobilien\/30350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/immobilien"}],"about":[{"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/types\/immobilien"}],"author":[{"embeddable":true,"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":6,"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/immobilien\/30350\/revisions"}],"predecessor-version":[{"id":30656,"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/immobilien\/30350\/revisions\/30656"}],"wp:attachment":[{"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/media?parent=30350"}],"wp:term":[{"taxonomy":"immobilien_kategorie","embeddable":true,"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/immobilien_kategorie?post=30350"},{"taxonomy":"angebotsart","embeddable":true,"href":"https:\/\/www.immomallorca.es\/de\/wp-json\/wp\/v2\/angebotsart?post=30350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}